{"id":1868,"date":"2023-07-07T10:53:57","date_gmt":"2023-07-07T08:53:57","guid":{"rendered":"https:\/\/menschenfuertieregrenzenlos.at\/?page_id=1868"},"modified":"2025-05-09T12:16:06","modified_gmt":"2025-05-09T10:16:06","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1868\" class=\"elementor elementor-1868\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43e3d4c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43e3d4c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9fffc3e\" data-id=\"9fffc3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e495c84 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"1e495c84\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72b07bad\" data-id=\"72b07bad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ad3f55 elementor-widget__width-initial elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-global elementor-global-732 elementor-widget-nav-menu\" data-id=\"9ad3f55\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;dropdown&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;fas fa-caret-down&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-9ad3f55\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-44\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-45\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/ueber-uns\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u00dcber uns<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5772\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/ueber-uns\/unser-team\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Unser Team<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4881\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/ueber-uns\/ueber-uns-oesterreich\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">\u00d6sterreich<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4880\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/ueber-uns\/ueber-uns-rumaenien\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Rum\u00e4nien<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-404\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/kooperationen\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Kooperationen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4879\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/das-sagen-die-adoptanten\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Das sagen die Adoptanten<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1407\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/unsere-tiere-4\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Unsere Tiere<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4877\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/unsere-tiere-4\/unsere-tiere-katzen\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Katzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4878\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/unsere-tiere-4\/unsere-tiere-hunde\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Hunde<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1783\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/spenden-patenschaften\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Spenden &#038; Patenschaften<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4876\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/spenden-patenschaften\/spenden-patenschaften-spenden\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Spenden<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4875\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/spenden-patenschaften\/spenden-patenschaften-patenschaften\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Patenschaften<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4874\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/spenden-patenschaften\/spenden-patenschaften-spenden\/spenden-patenschaften-spenden-foerdermitglied-werden\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">F\u00f6rdermitglied werden<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-46\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/adoption-pflegestelle\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Adoption &#038; Pflegestelle<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4882\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/adoption-pflegestelle\/pflegestelle\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Pflegestelle<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4883\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/adoption-pflegestelle\/adoption-2\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Adoption<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-227\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/kontakt\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Kontakt<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4885\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Datenschutzerkl\u00e4rung<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7029\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/faq\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">FAQ<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-12731\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/wp-login.php\" class=\"elementor-item menu-link\" tabindex=\"-1\">Interner Login<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10616d7c elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"10616d7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">Datenschutzerkl\u00e4rung<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10c8971 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10c8971\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1aed95\" data-id=\"f1aed95\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-597749a elementor-widget elementor-widget-spacer\" data-id=\"597749a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47aadf8 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"47aadf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"n\">1<b>. Personenbezogene Daten\/Datenquelle\/Zweck der Datenverarbeitung<\/b><\/p>\n<p>Wir, der Tierschutzverein Menschen f\u00fcr Tiere grenzenlos &#8211; erheben, verarbeiten und nutzen Ihre personenbezogenen Daten zur Vertragserf\u00fcllung bzw. zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen.<br>Ohne diese Daten k\u00f6nnen wir den Vertrag mit Ihnen nicht abschlie\u00dfen bzw. erf\u00fcllen.<br>Nach Ende der gesetzlichen Aufbewahrungsfrist bzw. im Falle, dass es zu keiner Vermittlung kommt werden die bei uns gespeicherten Daten gel\u00f6scht.<\/p>\n<p>Ansonsten nutzen wir Ihre Daten nur mit Ihrer Einwilligung zu den mit Ihnen vereinbarten Zwecken oder wenn eine sonstige rechtliche Grundlage im Einklang mit der DSGVO vorliegt, z-B. zur Erf\u00fcllung rechtlicher Verpflichtungen; dies unter Einhaltung der Datenschutz- und zivilrechtlichen Bestimmungen, insbesondere der Europ\u00e4ischen Datenschutzgrundverordnung, dem \u00f6sterreichischen Datenschutzgesetz 2018 und dem deutschen Bundesdatenschutzgesetz 2017.<br>Eine erteilte Einwilligung kann jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen werden.<\/p>\n<p>Soweit erforderlich kann eine zul\u00e4ssige Datenverarbeitung auch zu Wahrung berechtigter Interessen des Vereins Menschen f\u00fcr Tiere grenzenlos und Dritter erfolgen, z.B. zur Rechtverfolgung, zum Schutz von Mitarbeitern, zur Abwicklung von Beschwerden etc.<\/p>\n<p>Personenbezogene Daten sind alle Daten, die Einzelangaben \u00fcber pers\u00f6nliche oder sachliche Verh\u00e4ltnisse enthalten, beispielsweise Name, Anschrift, Email-Adresse, Telefonnummer, Geburtsdatum, Alter, Geschlecht, F\u00fchrerschein\/Passnummer, Videoaufzeichnungen, Fotos, Stimmenaufnahmen von Personen sowie biometrische Daten wie etwa Fingerabdr\u00fccke.<\/p>\n<p>2<b>. Auskunft und L\u00f6schung<\/b><\/p>\n<p>Als Kunde oder Kundin bzw. generell als Betroffener haben Sie jederzeit das Recht auf Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung sowie ein Recht auf Berichtigung, Daten\u00fcbertragung, Widerspruch, Einschr\u00e4nkung der Bearbeitung sowie Sperrung oder L\u00f6schung unrichtiger bzw. unzul\u00e4ssig verarbeiteter Daten.<\/p>\n<p>Insoweit sich \u00c4nderungen Ihrer pers\u00f6nlichen Daten ergeben, ersuchen wir um entsprechende Mitteilung.<\/p>\n<p>Sie haben jederzeit das Recht, eine erteilte Einwilligung zur Nutzung Ihrer personenbezogenen Daten zu widerrufen. Ihre Eingabe auf Auskunft, L\u00f6schung, Berichtigung, Widerspruch und\/oder Daten\u00fcbertragung, im letztgenannten Fall, sofern damit nicht ein unverh\u00e4ltnism\u00e4\u00dfiger Aufwand verursacht wird, kann an die in Punkt 10. dieser Erkl\u00e4rung angef\u00fchrte Anschrift\/E-Mail Adresse gerichtet werden.<\/p>\n<p>Wenn Sie der Auffassung sind, dass die Verarbeitung Ihrer personenbezogenen Daten durch uns gegen das geltende Datenschutzrecht verst\u00f6\u00dft oder Ihre datenschutzrechtlichen Anspr\u00fcche in einer anderen Weise verletzt worden sind, besteht die M\u00f6glichkeit, sich bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu beschweren. In \u00d6sterreich zust\u00e4ndig ist hierf\u00fcr die Datenschutzbeh\u00f6rde, Wickenburggasse 8-10, 1080 Wien.<br>In Deutschland ist die zust\u00e4ndige Beh\u00f6rde der Bundesbeauftragte f\u00fcr den Datenschutz und die Informationsfreiheit, Husarenstra\u00dfe 30, 53117 Bonn.<\/p>\n<p>3<b>. Datensicherheit<\/b><\/p>\n<p>Der Schutz Ihrer personenbezogenen Daten erfolgt durch entsprechende organisatorische und technische Vorkehrungen. Diese Vorkehrungen betreffen insbesondere den Schutz vor unerlaubtem, rechtswidrigem oder auch zuf\u00e4lligem Zugriff, Verarbeitung, Verlust, Verwendung und Manipulation.<\/p>\n<p>Ungeachtet der Bem\u00fchungen der Einhaltung eines stets angemessenen hohen Standes der Sorgfaltsanforderungen kann nicht ausgeschlossen werden, dass Informationen, die Sie uns \u00fcber das Internet bekannt geben, von anderen Personen eingesehen und genutzt werden.<\/p>\n<p>Bitte beachten Sie, dass wir daher keine wie immer geartete Haftung f\u00fcr die Offenlegung von Informationen aufgrund nicht von uns verursachter Fehler bei der Daten\u00fcbertragung und\/oder unautorisiertem Zugriff durch Dritte \u00fcbernehmen (zB Hackerangriff auf Email-Account bzw. Telefon, Abfangen von Faxen).<\/p>\n<p>4.<b> Verwendung der Daten<\/b><\/p>\n<p>Wir werden die uns zur Verf\u00fcgung gestellten Daten nicht f\u00fcr andere Zwecke als die f\u00fcr die Vertragserf\u00fcllung bzw. durch Ihre Einwilligung oder sonst durch eine Bestimmung im Einklang mit der DSGVO gedeckten Zwecken verarbeiten.<\/p>\n<p>5. <b>\u00dcbermittlung von Daten an Dritte<\/b><\/p>\n<p>Eine Datenweitergabe an Dritte erfolgt nicht, mit Ausnahme zum Zweck der Vertragsabwicklung oder Erf\u00fcllung gesetzlicher Pflichten. Zur Erf\u00fcllung Ihres Auftrages bzw. gesetzlicher Pflichten ist es auch erforderlich, Ihre Daten an Dritte weiterzuleiten, z.B. die Weiterleitung Ihrer Daten zum Zwecke einer Vor- oder Nachkontrolle durch einen Dritten, die Weiterleitung ihrer Daten an einen Zustelldienst oder die Post zwecks Auslieferung einer Bestellung, sowie an unsere Bilanzbuchhalterin bzw. unseren<\/p>\n<p>Steuerberater zur Erf\u00fcllung unserer buchhalterischen oder steuerrechtlichen Verpflichtungen zur Rechtsverfolgung an unsere Rechtsanw\u00e4lte etc.<\/p>\n<p>Eine Weiterleitung Ihrer Daten erfolgt ausschlie\u00dflich auf Grundlage der DSGVO. Es erfolgt jedenfalls keine Weiterleitung von Daten au\u00dferhalb der EU.<\/p>\n<p>6. <b>Bekanntgabe von Datenpannen<\/b><\/p>\n<p>Wir sind bem\u00fcht sicherzustellen, dass Datenpannen fr\u00fchzeitig erkannt und gegebenenfalls unverz\u00fcglich Ihnen bzw. der zust\u00e4ndigen Aufsichtsbeh\u00f6rde unter Einbezug der jeweiligen Datenkategorien, die betroffen sind, gemeldet werden.<\/p>\n<p>7.<b> Aufbewahrung der Daten<\/b><\/p>\n<p>Nach Ende der gesetzlichen Aufbewahrungsfrist bzw im Falle, dass es zu keiner Vermittlung kommt, werden die bei uns gespeicherten Daten gel\u00f6scht.<\/p>\n<p>8. <b>Cookies<\/b><\/p>\n<p>Diese Website verwendet \u201eCookies\u201c, um unser Angebot nutzerfreundlicher, effektiver und sicherer zu gestalten.<\/p>\n<p>Ein \u201eCookie\u201c ist eine kleine Textdatei, die wir \u00fcber unseren Web-Server an die Cookie-Datei des Browsers auf die Festplatte Ihres Computers \u00fcbermitteln. Damit wird es unserer Website erm\u00f6glicht, Sie als Nutzer wiederzuerkennen, wenn eine Verbindung zwischen unserem Web-Server und Ihrem Browser hergestellt wird. Cookies helfen uns dabei, die Nutzungsh\u00e4ufigkeit und die Anzahl der Nutzer unserer Internetseiten zu ermitteln. Der Inhalt der von uns verwendeten Cookies beschr\u00e4nkt sich auf eine Identifikationsnummer, die keine Personenbeziehbarkeit mehr auf den Nutzer zul\u00e4sst. Der Hauptzweck eines Cookies ist die Erkennung der Besucher der Website.<\/p>\n<p>Zwei Arten von Cookies werden auf dieser Website verwendet:<\/p>\n<p>\u2022 Session Cookies: Das sind tempor\u00e4re Cookies, die bis zum Verlassen unserer Website in der Cookie-Datei Ihres Browsers verweilen und nach Ende Ihres Besuchs automatisch gel\u00f6scht werden.<\/p>\n<p>\u2022 Dauerhafte Cookies: F\u00fcr eine bessere Benutzerfreundlichkeit bleiben Cookies auf Ihrem Endger\u00e4t gespeichert und erlauben es uns, Ihren Browser beim n\u00e4chsten Besuch wiederzuerkennen.<\/p>\n<p>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browsers aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p>\n<p>9. <b>Server-Log-Files<\/b><\/p>\n<p>Zur Optimierung dieser Website in Bezug auf die System-Performance, Benutzerfreundlichkeit und Bereitstellung von n\u00fctzlichen Informationen \u00fcber unsere Dienstleistungen erhebt und speichert der Provider der Website automatisch Informationen in so genannten Server-Log Files, die Ihr Browser automatisch an uns \u00fcbermittelt. Davon umfasst sind Ihre Internet-Protokoll Adresse (IP-Adresse), Browser und Spracheinstellung, Betriebssystem, Referrer URL, Ihr Internet Service Provider und Datum\/Uhrzeit.<\/p>\n<p>Eine Zusammenf\u00fchrung dieser Daten mit personenbezogenen Datenquellen wird nicht vorgenommen. Wir behalten uns vor, diese Daten nachtr\u00e4glich zu pr\u00fcfen, wenn uns konkrete Anhaltspunkte f\u00fcr eine rechtswidrige Nutzung bekannt werden.<\/p>\n<p>10. <b>Newsletter<\/b><\/p>\n<p>Sie haben die M\u00f6glichkeit, \u00fcber unsere Website unseren Newsletter zu abonnieren. Hierf\u00fcr ben\u00f6tigen wir Ihre E-Mail Adresse und Ihre Erkl\u00e4rung, dass Sie mit dem Bezug des Newsletters einverstanden sind. Das Abo des Newsletters k\u00f6nnen Sie jederzeit stornieren. Senden Sie ihre Stornierung bitte an folgende E-Mail Adresse menschenfuertieregrenzenlos@outlook.com.<br>Wir l\u00f6schen anschlie\u00dfend umgehend Ihre Daten im Zusammenhang mit dem Newsletter-Versand.<\/p>\n<p>11. <b>Unsere Kontaktdaten<\/b><\/p>\n<p>Der Schutz Ihrer Daten ist uns besonders wichtig. Wir sind f\u00fcr Sie unter den unten angef\u00fchrten Kontaktdaten jederzeit f\u00fcr Ihre Fragen oder Ihren Widerruf erreichbar.<\/p>\n<p>Tierschutzverein Menschen f\u00fcr Tiere grenzenlos<br>ZVR 388047885<br>Kaufing 60<br>4690 R\u00fcstorf<br>menschenfuertieregrenzenlos@outlook.com<\/p>\n<h2 class=\"n\">Hinweise zur Datenverarbeitung im Zusammenhang mit Google Analytics<\/h2>\n<div>&nbsp;<\/div>\n<p class=\"n\">Diese Website benutzt Google Analytics, einen Webanalysedienst der Google Ireland Limited. Wenn der Verantwortliche f\u00fcr die Datenverarbeitung auf dieser Website au\u00dferhalb des Europ\u00e4ischen Wirtschaftsraumes oder der Schweiz sitzt, dann erfolgt die Google Analytics Datenverarbeitung durch Google LLC. Google LLC und Google Ireland Limited werden nachfolgend &#8222;Google&#8220; genannt.<\/p>\n<p>Google Analytics verwendet sog. &#8222;Cookies&#8220;, Textdateien, die auf dem Computer des Seitenbesuchers gespeichert werden und die eine Analyse der Benutzung der Website durch den Seitenbesucher erm\u00f6glichen. Die durch das Cookie erzeugten Informationen \u00fcber die Benutzung dieser Website durch den Seitenbesucher (einschlie\u00dflich der gek\u00fcrzten IP-Adresse) werden in der Regel an einen Server von Google \u00fcbertragen und dort gespeichert.<\/p>\n<p>Google Analytics wird ausschlie\u00dflich mit der Erweiterung &#8222;_anonymizeIp()&#8220; auf dieser Website verwendet. Diese Erweiterung stellt eine Anonymisierung der IP-Adresse durch K\u00fcrzung sicher und schlie\u00dft eine direkte Personenbeziehbarkeit aus. Durch die Erweiterung wird die IP-Adresse von Google innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum zuvor gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Die im Rahmen von Google Analytics von dem entsprechenden Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt.<\/p>\n<p>Im Auftrag des Seitenbetreibers wird Google die anfallenden Informationen benutzen, um die Nutzung der Website auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen dem Seitenbetreiber gegen\u00fcber zu erbringen (Art. 6 Abs. 1 lit. f DSGVO). Das berechtigte Interesse an der Datenverarbeitung liegt in der Optimierung dieser Website, der Analyse der Benutzung der Website und der Anpassung der Inhalte. Die Interessen der Nutzer werden durch die Pseudonymisierung hinreichend gewahrt.<\/p>\n<p>Google LLC. bietet eine Garantie auf Basis der Standardvertragsklauseln ein angemessenes Datenschutzniveau einzuhalten. Die gesendeten und mit Cookies, Nutzerkennungen (z. B. User-ID) oder Werbe-IDs verkn\u00fcpften Daten werden nach 50 Monaten automatisch gel\u00f6scht. Die L\u00f6schung von Daten, deren Aufbewahrungsdauer erreicht ist, erfolgt automatisch einmal im Monat.<\/p>\n<p>Die Erfassung durch Google Analytics kann verhindert werden, indem der Seitenbesucher die Cookie-Einstellungen f\u00fcr diese Website anpasst. Der Erfassung und Speicherung der IP-Adresse und der durch Cookies erzeugten Daten kann au\u00dferdem jederzeit mit Wirkung f\u00fcr die Zukunft widersprochen werden. Das entsprechende Browser- Plugin kann unter dem folgenden Link heruntergeladen und installiert werden:&nbsp;<a href=\"http:\/\/tools.google.com\/dlpage\/gaoptout\" target=\"_blank\" rel=\"noopener\">https:\/\/tools.google.com\/dlpage\/gaoptout<\/a>.<\/p>\n<p><span class=\"jtpl-ga-opt-out-text \">Der Seitenbesucher kann die Erfassung durch Google Analytics auf dieser Webseite verhindern, indem er auf folgenden&nbsp;<a class=\"ga-opt-out-link\">Link<\/a>&nbsp;klickt. Es wird ein Opt-Out-Cookie gesetzt, der die zuk\u00fcnftige Erfassung der Daten beim Besuch dieser Website verhindert.<\/span><\/p>\n<p>Weitere Informationen zur Datennutzung durch Google, Einstellungs- und Widerspruchsm\u00f6glichkeiten, finden sich in der Datenschutzerkl\u00e4rung von Google (<a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy<\/a>) sowie in den Einstellungen f\u00fcr die Darstellung von Werbeeinblendungen durch Google (<a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noopener\">https:\/\/adssettings.google.com\/authenticated<\/a>).<\/p>\n<h2 class=\"n\">reCAPTCHA<\/h2>\n<div>&nbsp;<\/div>\n<p class=\"n\">Zum Schutz Ihrer Anfragen per Internetformular verwenden wir den Dienst reCAPTCHA des Unternehmens Google LLC (Google). Die Abfrage dient der Unterscheidung, ob die Eingabe durch einen Menschen oder missbr\u00e4uchlich durch automatisierte, maschinelle Verarbeitung erfolgt. Die Abfrage schlie\u00dft den Versand der IP-Adresse und ggf. weiterer von Google f\u00fcr den Dienst reCAPTCHA ben\u00f6tigter Daten an Google ein. Zu diesem Zweck wird Ihre Eingabe an Google \u00fcbermittelt und dort weiter verwendet. Ihre IP-Adresse wird von Google jedoch innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum zuvor gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Im Auftrag des Betreibers dieser Website wird Google diese Informationen benutzen, um Ihre Nutzung dieses Dienstes auszuwerten. Die im Rahmen von reCaptcha von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt. F\u00fcr diese Daten gelten die abweichenden Datenschutzbestimmungen des Unternehmens Google. Weitere Informationen zu den Datenschutzrichtlinien von Google finden Sie unter:&nbsp;<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy?hl=de<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1560576 elementor-widget elementor-widget-spacer\" data-id=\"1560576\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-976d99a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"976d99a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dfb5f3e\" data-id=\"dfb5f3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-652b9c59 elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"652b9c59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tierschutzverein<br \/><strong>Menschen f\u00fcr Tiere grenzenlos<\/strong><br \/>Kaufing 60<br \/>4690 R\u00fcstorf<br \/>0676\/64 16 884<br \/>menschenfuertieregrenzenlos@outlook.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4b6817e\" data-id=\"4b6817e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ffc42f0 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"2ffc42f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-grow elementor-repeater-item-b738a0b\" href=\"https:\/\/www.facebook.com\/menschenfuertiergrenzenlos\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-grow elementor-repeater-item-eb42c83\" href=\"https:\/\/instagram.com\/menschen_fuer_tiere_grenzenlos?igshid=MzNlNGNkZWQ4Mg==\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5af73ce0 elementor-widget elementor-widget-text-editor\" data-id=\"5af73ce0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Folge uns<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1253d34\" data-id=\"1253d34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5190a4c6 elementor-nav-menu__align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"5190a4c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-grow\">\n\t\t\t\t<ul id=\"menu-1-5190a4c6\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-44\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/\" class=\"elementor-item menu-link\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-45\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/ueber-uns\/\" class=\"elementor-item menu-link\">\u00dcber uns<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5772\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/ueber-uns\/unser-team\/\" class=\"elementor-sub-item menu-link\">Unser Team<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4881\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/ueber-uns\/ueber-uns-oesterreich\/\" class=\"elementor-sub-item menu-link\">\u00d6sterreich<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4880\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/ueber-uns\/ueber-uns-rumaenien\/\" class=\"elementor-sub-item menu-link\">Rum\u00e4nien<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-404\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/kooperationen\/\" class=\"elementor-sub-item menu-link\">Kooperationen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4879\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/das-sagen-die-adoptanten\/\" class=\"elementor-sub-item menu-link\">Das sagen die Adoptanten<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1407\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/unsere-tiere-4\/\" class=\"elementor-item menu-link\">Unsere Tiere<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4877\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/unsere-tiere-4\/unsere-tiere-katzen\/\" class=\"elementor-sub-item menu-link\">Katzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4878\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/unsere-tiere-4\/unsere-tiere-hunde\/\" class=\"elementor-sub-item menu-link\">Hunde<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1783\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/spenden-patenschaften\/\" class=\"elementor-item menu-link\">Spenden &#038; Patenschaften<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4876\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/spenden-patenschaften\/spenden-patenschaften-spenden\/\" class=\"elementor-sub-item menu-link\">Spenden<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4875\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/spenden-patenschaften\/spenden-patenschaften-patenschaften\/\" class=\"elementor-sub-item menu-link\">Patenschaften<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4874\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/spenden-patenschaften\/spenden-patenschaften-spenden\/spenden-patenschaften-spenden-foerdermitglied-werden\/\" class=\"elementor-sub-item menu-link\">F\u00f6rdermitglied werden<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-46\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/adoption-pflegestelle\/\" class=\"elementor-item menu-link\">Adoption &#038; Pflegestelle<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4882\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/adoption-pflegestelle\/pflegestelle\/\" class=\"elementor-sub-item menu-link\">Pflegestelle<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4883\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/adoption-pflegestelle\/adoption-2\/\" class=\"elementor-sub-item menu-link\">Adoption<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-227\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/kontakt\/\" class=\"elementor-item menu-link\">Kontakt<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4885\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/\" class=\"elementor-sub-item menu-link\">Datenschutzerkl\u00e4rung<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7029\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/faq\/\" class=\"elementor-item menu-link\">FAQ<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-12731\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/wp-login.php\" class=\"elementor-item menu-link\">Interner Login<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-5190a4c6\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-44\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-45\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/ueber-uns\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u00dcber uns<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5772\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/ueber-uns\/unser-team\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Unser Team<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4881\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/ueber-uns\/ueber-uns-oesterreich\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">\u00d6sterreich<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4880\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/ueber-uns\/ueber-uns-rumaenien\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Rum\u00e4nien<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-404\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/kooperationen\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Kooperationen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4879\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/das-sagen-die-adoptanten\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Das sagen die Adoptanten<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1407\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/unsere-tiere-4\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Unsere Tiere<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4877\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/unsere-tiere-4\/unsere-tiere-katzen\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Katzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4878\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/unsere-tiere-4\/unsere-tiere-hunde\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Hunde<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1783\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/spenden-patenschaften\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Spenden &#038; Patenschaften<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4876\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/spenden-patenschaften\/spenden-patenschaften-spenden\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Spenden<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4875\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/spenden-patenschaften\/spenden-patenschaften-patenschaften\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Patenschaften<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4874\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/spenden-patenschaften\/spenden-patenschaften-spenden\/spenden-patenschaften-spenden-foerdermitglied-werden\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">F\u00f6rdermitglied werden<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-46\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/adoption-pflegestelle\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Adoption &#038; Pflegestelle<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4882\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/adoption-pflegestelle\/pflegestelle\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Pflegestelle<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4883\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/adoption-pflegestelle\/adoption-2\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Adoption<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-227\"><a aria-expanded=\"false\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/kontakt\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Kontakt<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4885\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Datenschutzerkl\u00e4rung<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7029\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/faq\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">FAQ<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-12731\"><a href=\"https:\/\/menschenfuertieregrenzenlos.at\/wp-login.php\" class=\"elementor-item menu-link\" tabindex=\"-1\">Interner Login<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung 1. Personenbezogene Daten\/Datenquelle\/Zweck der Datenverarbeitung Wir, der Tierschutzverein Menschen f\u00fcr Tiere grenzenlos &#8211; erheben, verarbeiten und nutzen Ihre personenbezogenen Daten zur Vertragserf\u00fcllung bzw. zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen.Ohne diese Daten k\u00f6nnen wir den Vertrag mit Ihnen nicht abschlie\u00dfen bzw. erf\u00fcllen.Nach Ende der gesetzlichen Aufbewahrungsfrist bzw. im Falle, dass es zu keiner Vermittlung kommt werden die [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"give_campaign_id":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1868","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutzerkl\u00e4rung -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung -\" \/>\n<meta property=\"og:description\" content=\"Datenschutzerkl\u00e4rung 1. Personenbezogene Daten\/Datenquelle\/Zweck der Datenverarbeitung Wir, der Tierschutzverein Menschen f\u00fcr Tiere grenzenlos &#8211; erheben, verarbeiten und nutzen Ihre personenbezogenen Daten zur Vertragserf\u00fcllung bzw. zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen.Ohne diese Daten k\u00f6nnen wir den Vertrag mit Ihnen nicht abschlie\u00dfen bzw. erf\u00fcllen.Nach Ende der gesetzlichen Aufbewahrungsfrist bzw. im Falle, dass es zu keiner Vermittlung kommt werden die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/menschenfuertiergrenzenlos\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T10:16:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/index.php\\\/datenschutzerklaerung\\\/\",\"url\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/index.php\\\/datenschutzerklaerung\\\/\",\"name\":\"Datenschutzerkl\u00e4rung -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/#website\"},\"datePublished\":\"2023-07-07T08:53:57+00:00\",\"dateModified\":\"2025-05-09T10:16:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/index.php\\\/datenschutzerklaerung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/index.php\\\/datenschutzerklaerung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/index.php\\\/datenschutzerklaerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/#website\",\"url\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/\",\"name\":\"Menschen f\u00fcr Tiere grenzenlos\",\"description\":\"Menschen f\u00fcr Tiere grenzenlos\",\"publisher\":{\"@id\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/#organization\",\"name\":\"Menschen f\u00fcr Tiere grenzenlos\",\"url\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/MfTg_Logo_rgb.svg\",\"contentUrl\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/MfTg_Logo_rgb.svg\",\"width\":127,\"height\":202,\"caption\":\"Menschen f\u00fcr Tiere grenzenlos\"},\"image\":{\"@id\":\"https:\\\/\\\/menschenfuertieregrenzenlos.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/menschenfuertiergrenzenlos\\\/\",\"https:\\\/\\\/www.instagram.com\\\/menschen_fuer_tiere_grenzenlos\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutzerkl\u00e4rung -","og_description":"Datenschutzerkl\u00e4rung 1. Personenbezogene Daten\/Datenquelle\/Zweck der Datenverarbeitung Wir, der Tierschutzverein Menschen f\u00fcr Tiere grenzenlos &#8211; erheben, verarbeiten und nutzen Ihre personenbezogenen Daten zur Vertragserf\u00fcllung bzw. zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen.Ohne diese Daten k\u00f6nnen wir den Vertrag mit Ihnen nicht abschlie\u00dfen bzw. erf\u00fcllen.Nach Ende der gesetzlichen Aufbewahrungsfrist bzw. im Falle, dass es zu keiner Vermittlung kommt werden die [&hellip;]","og_url":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/","article_publisher":"https:\/\/www.facebook.com\/menschenfuertiergrenzenlos\/","article_modified_time":"2025-05-09T10:16:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/","url":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/","name":"Datenschutzerkl\u00e4rung -","isPartOf":{"@id":"https:\/\/menschenfuertieregrenzenlos.at\/#website"},"datePublished":"2023-07-07T08:53:57+00:00","dateModified":"2025-05-09T10:16:06+00:00","breadcrumb":{"@id":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/menschenfuertieregrenzenlos.at\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/menschenfuertieregrenzenlos.at\/#website","url":"https:\/\/menschenfuertieregrenzenlos.at\/","name":"Menschen f\u00fcr Tiere grenzenlos","description":"Menschen f\u00fcr Tiere grenzenlos","publisher":{"@id":"https:\/\/menschenfuertieregrenzenlos.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/menschenfuertieregrenzenlos.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/menschenfuertieregrenzenlos.at\/#organization","name":"Menschen f\u00fcr Tiere grenzenlos","url":"https:\/\/menschenfuertieregrenzenlos.at\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/menschenfuertieregrenzenlos.at\/#\/schema\/logo\/image\/","url":"https:\/\/menschenfuertieregrenzenlos.at\/wp-content\/uploads\/2025\/06\/MfTg_Logo_rgb.svg","contentUrl":"https:\/\/menschenfuertieregrenzenlos.at\/wp-content\/uploads\/2025\/06\/MfTg_Logo_rgb.svg","width":127,"height":202,"caption":"Menschen f\u00fcr Tiere grenzenlos"},"image":{"@id":"https:\/\/menschenfuertieregrenzenlos.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/menschenfuertiergrenzenlos\/","https:\/\/www.instagram.com\/menschen_fuer_tiere_grenzenlos\/"]}]}},"campaignId":"","_links":{"self":[{"href":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/wp-json\/wp\/v2\/pages\/1868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/wp-json\/wp\/v2\/comments?post=1868"}],"version-history":[{"count":3,"href":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/wp-json\/wp\/v2\/pages\/1868\/revisions"}],"predecessor-version":[{"id":9420,"href":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/wp-json\/wp\/v2\/pages\/1868\/revisions\/9420"}],"wp:attachment":[{"href":"https:\/\/menschenfuertieregrenzenlos.at\/index.php\/wp-json\/wp\/v2\/media?parent=1868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}